{"id":2134,"date":"2023-10-25T04:22:34","date_gmt":"2023-10-25T10:22:34","guid":{"rendered":"https:\/\/littlebellies.com\/ca\/?p=2134"},"modified":"2026-07-26T08:30:53","modified_gmt":"2026-07-26T14:30:53","slug":"guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade","status":"publish","type":"post","link":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/","title":{"rendered":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir un guide pratique des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Quand mon b\u00e9b\u00e9 est-il pr\u00eat \u00e0 manger des aliments solides?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Les b\u00e9b\u00e9s commenceront \u00e0 montrer des signes indiquant qu\u2019ils sont pr\u00eats \u00e0 commencer \u00e0 en manger vers l\u2019\u00e2ge de 6&nbsp;mois. Les signes \u00e0 observer sont les suivants&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Commencer \u00e0 porter \u00e0 la bouche des jouets et des objets<\/li>\n\n\n\n<li>Avoir un bon contr\u00f4le de la t\u00eate et du cou<\/li>\n\n\n\n<li>S\u2019asseoir avec peu ou pas de soutien<\/li>\n\n\n\n<li>Pousser les jouets hors de la bouche avec la langue moins souvent (c\u2019est-\u00e0-dire, avoir int\u00e9gr\u00e9 le r\u00e9flexe d\u2019extrusion de la langue)<\/li>\n\n\n\n<li>Montrer de l\u2019int\u00e9r\u00eat pour la nourriture<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le b\u00e9b\u00e9 doit pr\u00e9senter ces signes avant de commencer \u00e0 manger des aliments solides. La majorit\u00e9 des b\u00e9b\u00e9s montrent ces signes vers l\u2019\u00e2ge de 6&nbsp;mois. Si votre b\u00e9b\u00e9 ne pr\u00e9sente pas ces signes ou si vous avez des questions, contactez votre p\u00e9diatre pour obtenir des conseils personnalis\u00e9s sur le moment appropri\u00e9 pour commencer \u00e0 lui donner des aliments solides.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Le premier repas<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Il peut \u00eatre angoissant de donner pour la premi\u00e8re fois de la nourriture \u00e0 son b\u00e9b\u00e9!&nbsp;<em>Que dois-je offrir? Comment dois-je le nourrir? Quelle quantit\u00e9 dois-je lui donner? \u00c0 quelle fr\u00e9quence dois-je le nourrir?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous donnez de la nourriture \u00e0 votre b\u00e9b\u00e9 pour la premi\u00e8re fois, sachez que vous avez le choix. Certaines personnes choisiront de donner des c\u00e9r\u00e9ales pour b\u00e9b\u00e9s fortifi\u00e9es avec du fer, comme le gruau, tandis que d\u2019autres opteront pour un fruit ou un l\u00e9gume. En g\u00e9n\u00e9ral, les b\u00e9b\u00e9s acceptent bien les fruits en raison de leur go\u00fbt sucr\u00e9. Le lait maternel ou les pr\u00e9parations commerciales pour nourrissons qu\u2019ils ont consomm\u00e9s jusqu\u2019\u00e0 pr\u00e9sent sont \u00e9galement sucr\u00e9s, de sorte qu\u2019il s\u2019agit d\u2019une suite logique pour eux. Certaines familles choisissent de proposer 2 ou 3&nbsp;options d\u2019aliments. Choisissez ce qui vous convient le mieux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si votre b\u00e9b\u00e9 a 6&nbsp;mois et qu\u2019il est capable de s\u2019asseoir avec peu ou pas de soutien, la diversification alimentaire men\u00e9e par l\u2019enfant (DME) peut \u00eatre une option \u00e0 envisager. Il s\u2019agit de proposer des morceaux d\u2019aliments en forme de b\u00e2tonnets que le b\u00e9b\u00e9 prend et mange lui-m\u00eame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous pr\u00e9f\u00e9rez une approche plus traditionnelle, vous pouvez lui donner des aliments en pur\u00e9e ou \u00e9cras\u00e9s \u00e0 la cuill\u00e8re. En observant les signaux de votre b\u00e9b\u00e9, vous saurez s\u2019il veut manger davantage ou s\u2019il a termin\u00e9. Les signaux indiquant qu\u2019il en veut \u00ab&nbsp;plus&nbsp;\u00bb sont les suivants&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ouvrir la bouche<\/li>\n\n\n\n<li>Se pencher vers la cuill\u00e8re<\/li>\n\n\n\n<li>Essayer d\u2019attraper la cuill\u00e8re<\/li>\n\n\n\n<li>Se montrer excit\u00e9 \u00e0 la vue de la nourriture<\/li>\n\n\n\n<li>Exprimer des signes verbaux<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque votre b\u00e9b\u00e9 montre des signes de sati\u00e9t\u00e9, il est temps de mettre fin au repas, quelle que soit la quantit\u00e9 de nourriture qu\u2019il a mang\u00e9e. Les signes indiquant que l\u2019enfant a \u00ab&nbsp;fini&nbsp;\u00bb de manger peuvent ressembler \u00e0 ce qui suit&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se pincer les l\u00e8vres pour ne pas laisser entrer la nourriture<\/li>\n\n\n\n<li>Tourner la t\u00eate sur le c\u00f4t\u00e9<\/li>\n\n\n\n<li>Devenir plus distrait<\/li>\n\n\n\n<li>Jeter ou recracher de la nourriture<\/li>\n\n\n\n<li>Pleurer ou \u00eatre irritable<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>De 6 \u00e0 7 mois<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nombre de repas&nbsp;: de 1 \u00e0 2&nbsp;repas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de <strong><a href=\"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/introduction-des-aliments-solides-chez-le-bebe-un-guide-pour-les-parents\/\" title=\"\">l\u2019introduction des aliments solides<\/a><\/strong>, un seul repas par jour suffit. Pendant les premi\u00e8res semaines o\u00f9 l\u2019on commence \u00e0 offrir des aliments, il y a bien des apprentissages \u00e0 faire (et peu de nourriture r\u00e9ellement consomm\u00e9e). C\u2019est normal et attendu. Au fur et \u00e0 mesure que votre enfant apprendra et d\u00e9veloppera ses comp\u00e9tences en mati\u00e8re d\u2019alimentation, la quantit\u00e9 de nourriture qu\u2019il ou elle consomme augmentera. Vers l\u2019\u00e2ge de 7\u00a0mois, il est souvent opportun de passer \u00e0 deux repas par jour.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tences li\u00e9es \u00e0 l\u2019alimentation&nbsp;: Prise palmaire<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prise palmaire consiste \u00e0 enrouler la main autour d\u2019un objet (par exemple, saisir un b\u00e2ton). Cette capacit\u00e9 permet au b\u00e9b\u00e9 de tenir des aliments en forme de b\u00e2ton ainsi que des cuill\u00e8res. \u00c0 cet \u00e2ge, les b\u00e9b\u00e9s n\u2019ont g\u00e9n\u00e9ralement pas encore la capacit\u00e9 de manger avec une cuill\u00e8re. Ce que vous pouvez faire, c\u2019est remplir la cuill\u00e8re et la donner au b\u00e9b\u00e9 pour qu\u2019il se nourrisse lui-m\u00eame s\u2019il le souhaite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Textures (m\u00e9thode traditionnelle)&nbsp;: Nourriture en pur\u00e9e ou \u00e9cras\u00e9e.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la plupart des b\u00e9b\u00e9s, les pur\u00e9es constituent la premi\u00e8re transition vers les textures alimentaires. Le choix d\u2019un m\u00e9lange lisse au d\u00e9but peut aider votre b\u00e9b\u00e9 \u00e0 s\u2019habituer \u00e0 cette nouvelle texture. Vous pouvez choisir des pur\u00e9es tr\u00e8s fines et d\u2019autres plus \u00e9paisses. Apr\u00e8s avoir propos\u00e9 ces textures pendant quelques semaines, vous pouvez passer aux textures \u00e9cras\u00e9es qui contiennent des grumeaux.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>De 8 \u00e0 9 mois<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nombre de repas&nbsp;: de 2 \u00e0 3&nbsp;repas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque votre b\u00e9b\u00e9 s\u2019habitue \u00e0 manger des aliments solides deux fois par jour, vous pouvez augmenter le nombre de repas \u00e0 trois. Il peut s\u2019agir du d\u00e9jeuner, du d\u00eener et du souper. Pour d\u2019autres, servir deux repas et une collation peut \u00eatre mieux adapt\u00e9 \u00e0 leur emploi du temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tences li\u00e9es \u00e0 l\u2019alimentation&nbsp;: Pince fine<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cet \u00e2ge, les b\u00e9b\u00e9s d\u00e9veloppent leur prise en pince fine. Vous constaterez qu\u2019il y a plusieurs stades entre la prise palmaire et la prise en pince. Ils saisissent parfois des jouets ou des morceaux de nourriture avec leur pouce et quelques doigts. Ils acquerront progressivement la capacit\u00e9 de prendre des cubes de nourriture avec leur pouce et leur index (pince fine).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Textures&nbsp;: Cubes mous<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en pince fine offre une nouvelle possibilit\u00e9! B\u00e9b\u00e9 sera capable de saisir de petits morceaux d\u2019aliments comme les souffl\u00e9s qui fondent dans la bouche de la gamme <strong><a href=\"https:\/\/littlebellies.com\/ca\/fr\/snacks-by-age\/7-mois-et-plus\/\" title=\"\">TEXTURES SAVOUREUSES<\/a><\/strong> de Little Bellies pour les b\u00e9b\u00e9s de 7\u00a0mois et plus, con\u00e7us pour une alimentation autonome s\u00e9curitaire. \u00c0 ce stade, les aliments doivent \u00eatre assez tendres pour qu\u2019une fourchette puisse les transpercer et faciles \u00e0 \u00e9craser. Les petits cubes d\u2019aliments bien cuits permettent \u00e0 votre b\u00e9b\u00e9 de s\u2019alimenter seul en toute s\u00e9curit\u00e9.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>De 10 \u00e0 12&nbsp;mois<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nombre de repas&nbsp;: 3&nbsp;repas, 0 \u00e0 1&nbsp;collation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l\u2019\u00e2ge de 10&nbsp;mois, votre enfant sera capable de manger trois repas par jour. Certaines familles constateront \u00e0 cet \u00e2ge que leur b\u00e9b\u00e9 boit moins de lait (au sein ou au biberon) et qu\u2019il pourrait avoir besoin d\u2019une collation suppl\u00e9mentaire. Lorsque vous servez une collation, veillez \u00e0 ce qu\u2019elle soit bien \u00e9quilibr\u00e9e et contienne des mati\u00e8res grasses ou des prot\u00e9ines ainsi qu\u2019un aliment sain riche en glucides.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tences li\u00e9es \u00e0 l\u2019alimentation&nbsp;: Mastication habile, ind\u00e9pendance accrue<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mastication devient beaucoup plus facile pour votre b\u00e9b\u00e9, car sa m\u00e2choire d\u00e9veloppe des mouvements rotatifs. Vous remarquerez peut-\u00eatre que votre b\u00e9b\u00e9 veut participer davantage au processus d\u2019alimentation, par exemple en prenant la nourriture avec sa cuill\u00e8re.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Textures&nbsp;: Cubes et morceaux d\u2019aliments coup\u00e9s.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Votre b\u00e9b\u00e9 devient plus habile \u00e0 manger des morceaux de nourriture gr\u00e2ce aux nouveaux mouvements de sa m\u00e2choire. Cela vous permet de lui servir des aliments de diff\u00e9rentes textures, comme de la viande effiloch\u00e9e, des morceaux de fromage, des raisins en d\u00e9s et des aliments solides fondants. En ce qui concerne les collations, vous pouvez maintenant passer \u00e0 des formes et \u00e0 des textures plus complexes comme celles de la gamme de collations\u00a0<strong><a href=\"https:\/\/littlebellies.com\/ca\/fr\/snacks-by-age\/10-mois-et-plus\/\" title=\"\">TANT \u00c0 EXPLORER<\/a><\/strong>\u00a0de Little Bellies pour les b\u00e9b\u00e9s de 10\u00a0mois et plus.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1&nbsp;an et plus!<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nombre de repas&nbsp;: 3 repas, 2 \u00e0 3&nbsp;collations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au fur et \u00e0 mesure que votre tout-petit est moins allait\u00e9 ou boit moins de biberons et que la nourriture devient l\u2019\u00e9l\u00e9ment principal de son alimentation, les collations viendront combler ses besoins. Comme nous l\u2019avons d\u00e9j\u00e0 mentionn\u00e9, il faut veiller \u00e0 ce que ces collations soient tr\u00e8s nutritives! Offrez des aliments riches en fibres, en fer et en bon gras, tout en limitant ceux qui sont riches en sucres ajout\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tences li\u00e9es \u00e0 l\u2019alimentation&nbsp;: Ma\u00eetrise de la motricit\u00e9 fine<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Votre jeune enfant est maintenant un de l\u2019alimentation! &nbsp;Il mange une grande vari\u00e9t\u00e9 de textures, de formes et de tailles d\u2019aliments. En prenant des bouch\u00e9es raisonnables et en mastiquant plus soigneusement, les tout-petits ont acc\u00e8s \u00e0 un plus grand nombre d\u2019options alimentaires. Ils deviennent aussi progressivement plus habiles avec les ustensiles (et se salissent moins). Comme ils parviennent \u00e0 mieux fermer leurs l\u00e8vres en m\u00e2chant et en avalant, moins d\u2019aliments sont renvers\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Textures&nbsp;:<\/strong> <strong>Une multitude d\u2019options! Jetez un coup d\u2019\u0153il aux d\u00e9licieuses options de la gamme de Little Bellies pour les tout-petits<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 ce stade, il y a beaucoup moins de limites \u00e0 ce que votre tout-petit peut manger. De nombreux aliments que votre famille est habitu\u00e9e \u00e0 manger peuvent \u00eatre servis avec quelques petites modifications, au besoin. Les aliments qui pr\u00e9sentent des risques d\u2019\u00e9touffement restent les principales limites jusqu\u2019\u00e0 l\u2019\u00e2ge de 4&nbsp;ans. Parmi ceux-ci, citons les noix, les raisins et les baies entiers, les guimauves, le ma\u00efs souffl\u00e9, les grosses tranches de pommes, les cuiller\u00e9es de beurre de noix, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bon app\u00e9tit!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auteure&nbsp;: Nicole Lattanzio, RDN, IBCLC&nbsp;<em>@infant.nutritionist<\/em><br><em>Propri\u00e9taire, The Baby Dietitian PLLC<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Photo de&nbsp;<a href=\"https:\/\/unsplash.com\/@okkpr?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noreferrer noopener\">Olga Kisiel-Konopka<\/a>&nbsp;sur&nbsp;<a href=\"https:\/\/unsplash.com\/photos\/IW9flBDpy2I?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noreferrer noopener\">Unsplash<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1398,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"[]"},"categories":[272,276],"tags":[],"class_list":["post-2134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-age-et-stade","category-collations-positives"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nicole Lattanzio, RDN, CSP, IBCLC\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Little Bellies Organic Snacks &amp; Food for Babies &amp; Toddlers\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.\" \/>\n\t\t<meta property=\"og:description\" content=\"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-25T10:22:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-26T14:30:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LittleBellies\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.\" \/>\n\t\t<meta name=\"twitter:description\" content=\"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#article\",\"name\":\"Guide des aliments et des collations pour b\\u00e9b\\u00e9s par \\u00e2ge et par stade.\",\"headline\":\"Guide des aliments et des collations pour b\\u00e9b\\u00e9s par \\u00e2ge et par stade\",\"author\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/learn-play\\\/author\\\/nicole-lattanzio-rdn-csp-ibclc\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg\",\"width\":1030,\"height\":677},\"datePublished\":\"2023-10-25T04:22:34-06:00\",\"dateModified\":\"2026-07-26T08:30:53-06:00\",\"inLanguage\":\"en-AU\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#webpage\"},\"articleSection\":\"\\u00c2ge et stade, Collations positives, Fran\\u00e7ais, pll_6538ec6ad3c2c\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/littlebellies.com\\\/ca\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/category\\\/age-et-stade\\\/#listItem\",\"name\":\"\\u00c2ge et stade\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/category\\\/age-et-stade\\\/#listItem\",\"position\":2,\"name\":\"\\u00c2ge et stade\",\"item\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/category\\\/age-et-stade\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#listItem\",\"name\":\"Guide des aliments et des collations pour b\\u00e9b\\u00e9s par \\u00e2ge et par stade\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#listItem\",\"position\":3,\"name\":\"Guide des aliments et des collations pour b\\u00e9b\\u00e9s par \\u00e2ge et par stade\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/category\\\/age-et-stade\\\/#listItem\",\"name\":\"\\u00c2ge et stade\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/#organization\",\"name\":\"Little Bellies\",\"description\":\"Do What's Natural\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/wp-content\\\/uploads\\\/LB_Logo-272x300-1.jpg\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/littlebellies\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@littlebellies\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCX0iWNQFJc4cLucPRGlnpqw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/every-bite-counts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/learn-play\\\/author\\\/nicole-lattanzio-rdn-csp-ibclc\\\/#author\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/learn-play\\\/author\\\/nicole-lattanzio-rdn-csp-ibclc\\\/\",\"name\":\"Nicole Lattanzio, RDN, CSP, IBCLC\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/infant.nutritionist\\\/?hl=en\",\"https:\\\/\\\/www.pinterest.com\\\/nlattanziordn\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nicole-lattanzio-rd-ibclc\\\/\",\"https:\\\/\\\/www.threads.com\\\/@infant.nutritionist\"],\"description\":\"Nicole is passionate about improving how we support newborn feeding, nutrition, and lactation - especially in NICU environments where every decision matters. Her work has centered on understanding the day-to-day challenges care teams face and translating those into more thoughtful, effective systems. From human milk management to feeding workflows, she's driven to make processes safer, more intuitive, and easier to execute under pressure.\",\"jobTitle\":\"Pediatric Registered Dietitian & Board-Certified Specialist in Pediatric Nutrition\",\"knowsAbout\":[{\"@type\":\"Thing\",\"name\":\"Baby Food\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Baby_food\"},{\"@type\":\"Thing\",\"name\":\"Infant Feeding\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Infant_feeding\"},{\"@type\":\"Thing\",\"name\":\"Toddler Nutrition\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Toddler_nutrition\"},{\"@type\":\"Thing\",\"name\":\"Baby-led weaning\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Baby-led_weaning\"},{\"@type\":\"Thing\",\"name\":\"Registered dietitian nutritionists\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Dietitian\"},{\"@type\":\"Thing\",\"name\":\"Pediatric Nutrition\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Nutritionist\"}],\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#authorImage\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/wp-content\\\/uploads\\\/Nicole-Lattanzio-RD-IBCLC-CNSC.jpg\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#webpage\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/\",\"name\":\"Guide des aliments et des collations pour b\\u00e9b\\u00e9s par \\u00e2ge et par stade.\",\"description\":\"L\\u2019introduction des aliments solides peut \\u00eatre une \\u00e9tape \\u00e9prouvante. Alors que vous avez enfin \\u00e9tabli votre routine avec l\\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \\u00e9tape de la vie avec son lot d\\u2019apprentissages. N\\u2019ayez crainte, nous sommes l\\u00e0 pour vous aider! Lisez la suite pour obtenir\",\"inLanguage\":\"en-AU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/learn-play\\\/author\\\/nicole-lattanzio-rdn-csp-ibclc\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/learn-play\\\/author\\\/nicole-lattanzio-rdn-csp-ibclc\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#mainImage\",\"width\":1030,\"height\":677},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/fr\\\/learn-play\\\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\\\/#mainImage\"},\"datePublished\":\"2023-10-25T04:22:34-06:00\",\"dateModified\":\"2026-07-26T08:30:53-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/\",\"name\":\"Little Bellies\",\"description\":\"Do What's Natural\",\"inLanguage\":\"en-AU\",\"publisher\":{\"@id\":\"https:\\\/\\\/littlebellies.com\\\/ca\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.<\/title>\n\n","aioseo_head_json":{"title":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.","description":"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir","canonical_url":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#article","name":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.","headline":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade","author":{"@id":"https:\/\/littlebellies.com\/ca\/learn-play\/author\/nicole-lattanzio-rdn-csp-ibclc\/#author"},"publisher":{"@id":"https:\/\/littlebellies.com\/ca\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg","width":1030,"height":677},"datePublished":"2023-10-25T04:22:34-06:00","dateModified":"2026-07-26T08:30:53-06:00","inLanguage":"en-AU","mainEntityOfPage":{"@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#webpage"},"isPartOf":{"@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#webpage"},"articleSection":"\u00c2ge et stade, Collations positives, Fran\u00e7ais, pll_6538ec6ad3c2c"},{"@type":"BreadcrumbList","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca#listItem","position":1,"name":"Home","item":"https:\/\/littlebellies.com\/ca","nextItem":{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/category\/age-et-stade\/#listItem","name":"\u00c2ge et stade"}},{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/category\/age-et-stade\/#listItem","position":2,"name":"\u00c2ge et stade","item":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/category\/age-et-stade\/","nextItem":{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#listItem","name":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade"},"previousItem":{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#listItem","position":3,"name":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade","previousItem":{"@type":"ListItem","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/category\/age-et-stade\/#listItem","name":"\u00c2ge et stade"}}]},{"@type":"Organization","@id":"https:\/\/littlebellies.com\/ca\/#organization","name":"Little Bellies","description":"Do What's Natural","url":"https:\/\/littlebellies.com\/ca\/","logo":{"@type":"ImageObject","url":"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/LB_Logo-272x300-1.jpg","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#organizationLogo"},"image":{"@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/littlebellies\/","https:\/\/www.tiktok.com\/@littlebellies","https:\/\/www.youtube.com\/channel\/UCX0iWNQFJc4cLucPRGlnpqw","https:\/\/www.linkedin.com\/company\/every-bite-counts\/"]},{"@type":"Person","@id":"https:\/\/littlebellies.com\/ca\/learn-play\/author\/nicole-lattanzio-rdn-csp-ibclc\/#author","url":"https:\/\/littlebellies.com\/ca\/learn-play\/author\/nicole-lattanzio-rdn-csp-ibclc\/","name":"Nicole Lattanzio, RDN, CSP, IBCLC","sameAs":["https:\/\/www.instagram.com\/infant.nutritionist\/?hl=en","https:\/\/www.pinterest.com\/nlattanziordn\/","https:\/\/www.linkedin.com\/in\/nicole-lattanzio-rd-ibclc\/","https:\/\/www.threads.com\/@infant.nutritionist"],"description":"Nicole is passionate about improving how we support newborn feeding, nutrition, and lactation - especially in NICU environments where every decision matters. Her work has centered on understanding the day-to-day challenges care teams face and translating those into more thoughtful, effective systems. From human milk management to feeding workflows, she's driven to make processes safer, more intuitive, and easier to execute under pressure.","jobTitle":"Pediatric Registered Dietitian & Board-Certified Specialist in Pediatric Nutrition","knowsAbout":[{"@type":"Thing","name":"Baby Food","url":"https:\/\/en.wikipedia.org\/wiki\/Baby_food"},{"@type":"Thing","name":"Infant Feeding","url":"https:\/\/en.wikipedia.org\/wiki\/Infant_feeding"},{"@type":"Thing","name":"Toddler Nutrition","url":"https:\/\/en.wikipedia.org\/wiki\/Toddler_nutrition"},{"@type":"Thing","name":"Baby-led weaning","url":"https:\/\/en.wikipedia.org\/wiki\/Baby-led_weaning"},{"@type":"Thing","name":"Registered dietitian nutritionists","url":"https:\/\/en.wikipedia.org\/wiki\/Dietitian"},{"@type":"Thing","name":"Pediatric Nutrition","url":"https:\/\/en.wikipedia.org\/wiki\/Nutritionist"}],"image":{"@type":"ImageObject","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#authorImage","url":"https:\/\/littlebellies.com\/wp-content\/uploads\/Nicole-Lattanzio-RD-IBCLC-CNSC.jpg"}},{"@type":"WebPage","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#webpage","url":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/","name":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.","description":"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir","inLanguage":"en-AU","isPartOf":{"@id":"https:\/\/littlebellies.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#breadcrumblist"},"author":{"@id":"https:\/\/littlebellies.com\/ca\/learn-play\/author\/nicole-lattanzio-rdn-csp-ibclc\/#author"},"creator":{"@id":"https:\/\/littlebellies.com\/ca\/learn-play\/author\/nicole-lattanzio-rdn-csp-ibclc\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg","@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#mainImage","width":1030,"height":677},"primaryImageOfPage":{"@id":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/#mainImage"},"datePublished":"2023-10-25T04:22:34-06:00","dateModified":"2026-07-26T08:30:53-06:00"},{"@type":"WebSite","@id":"https:\/\/littlebellies.com\/ca\/#website","url":"https:\/\/littlebellies.com\/ca\/","name":"Little Bellies","description":"Do What's Natural","inLanguage":"en-AU","publisher":{"@id":"https:\/\/littlebellies.com\/ca\/#organization"}}]},"og:locale":"en_US","og:site_name":"Little Bellies Organic Snacks &amp; Food for Babies &amp; Toddlers","og:type":"article","og:title":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.","og:description":"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir","og:url":"https:\/\/littlebellies.com\/ca\/fr\/learn-play\/guide-des-aliments-et-des-collations-pour-bebes-par-age-et-par-stade\/","og:image":"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg","og:image:secure_url":"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg","og:image:width":1030,"og:image:height":677,"article:published_time":"2023-10-25T10:22:34+00:00","article:modified_time":"2026-07-26T14:30:53+00:00","article:publisher":"https:\/\/www.facebook.com\/LittleBellies","twitter:card":"summary","twitter:title":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.","twitter:description":"L\u2019introduction des aliments solides peut \u00eatre une \u00e9tape \u00e9prouvante. Alors que vous avez enfin \u00e9tabli votre routine avec l\u2019allaitement ou le biberon, badaboum! il est temps de passer aux aliments solides. Une toute nouvelle \u00e9tape de la vie avec son lot d\u2019apprentissages. N\u2019ayez crainte, nous sommes l\u00e0 pour vous aider! Lisez la suite pour obtenir","twitter:image":"https:\/\/littlebellies.com\/ca\/wp-content\/uploads\/sites\/4\/Baby-Food-and-Snack-Guide-by-Age-and-Stage-1.jpg"},"aioseo_meta_data":{"post_id":"2134","title":"Guide des aliments et des collations pour b\u00e9b\u00e9s par \u00e2ge et par stade.","description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2023-10-25 10:09:01","updated":"2026-07-26 15:47:25","ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"seo_analyzer_scan_date":"2026-07-26 14:33:40","reviewed_by":"0","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"lang":"fr","translations":{"fr":2134,"en":1245},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/posts\/2134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/comments?post=2134"}],"version-history":[{"count":1,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/posts\/2134\/revisions"}],"predecessor-version":[{"id":3107,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/posts\/2134\/revisions\/3107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/media\/1398"}],"wp:attachment":[{"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/media?parent=2134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/categories?post=2134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/littlebellies.com\/ca\/wp-json\/wp\/v2\/tags?post=2134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}